{"id":14369,"date":"2019-11-08T13:20:48","date_gmt":"2019-11-08T12:20:48","guid":{"rendered":"https:\/\/busot.es\/publica\/?p=14369"},"modified":"2019-11-08T13:20:48","modified_gmt":"2019-11-08T12:20:48","slug":"n-ref-878-2018-ayuda-no-dineraria-con-poblacion-inferior-a-5000-h-para-la-reparacion-y-conservacion-de-caminos-de-tituraliridad-no-provincial-linea-1-anualidad-2019","status":"publish","type":"post","link":"https:\/\/busot.es\/publica\/2019\/11\/08\/n-ref-878-2018-ayuda-no-dineraria-con-poblacion-inferior-a-5000-h-para-la-reparacion-y-conservacion-de-caminos-de-tituraliridad-no-provincial-linea-1-anualidad-2019\/","title":{"rendered":"N\/Ref.:878\/2018 AYUDA NO DINERARIA CON POBLACI\u00d3N INFERIOR A 5000 H. PARA LA REPARACI\u00d3N Y CONSERVACI\u00d3N DE CAMINOS DE TITURALIRIDAD NO PROVINCIAL. LINEA 1. ANUALIDAD 2019"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-12204\" src=\"https:\/\/busot.es\/publica\/wp-content\/uploads\/2016\/08\/logo-azul-va-2.png\" alt=\"\" width=\"426\" height=\"243\" srcset=\"https:\/\/busot.es\/publica\/wp-content\/uploads\/2016\/08\/logo-azul-va-2.png 827w, https:\/\/busot.es\/publica\/wp-content\/uploads\/2016\/08\/logo-azul-va-2-300x171.png 300w, https:\/\/busot.es\/publica\/wp-content\/uploads\/2016\/08\/logo-azul-va-2-768x438.png 768w\" sizes=\"auto, (max-width: 426px) 100vw, 426px\" \/><\/p>\n<p>Por la Junta de Gobierno Local de la Excma. Diputaci\u00f3n Provincial de Alicante celebrada con fecha 30 de octubre de 2019, adopt\u00f3 el acuerdo de aprobar la concesi\u00f3n al AYUNTAMIENTO DE BUSOT con CIF N\u00fam. P0304600J, de una subvenci\u00f3n para la actuaci\u00f3n \u201cReparaciones en el camino la Alquedra\u201d por un importe de 5.000,00 euros, incluida en la Convocatoria de ayuda no dineraria con poblaci\u00f3n inferior a 5000 h. para la reparaci\u00f3n y conservaci\u00f3n de caminos de titularidad no provincial. L\u00ednea 1. Anualidad 2019 Lo que se publica para general conocimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por la Junta de Gobierno Local de la Excma. Diputaci\u00f3n Provincial de Alicante celebrada con fecha 30 de octubre de 2019, adopt\u00f3 el acuerdo de aprobar la concesi\u00f3n al AYUNTAMIENTO DE BUSOT con CIF N\u00fam. P0304600J, de una subvenci\u00f3n para la actuaci\u00f3n \u201cReparaciones en el camino la Alquedra\u201d por un importe de 5.000,00 euros, incluida [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12204,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-14369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-subvenciones"],"_links":{"self":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts\/14369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/comments?post=14369"}],"version-history":[{"count":1,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts\/14369\/revisions"}],"predecessor-version":[{"id":14370,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts\/14369\/revisions\/14370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/media\/12204"}],"wp:attachment":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/media?parent=14369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/categories?post=14369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/tags?post=14369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}