{"id":14084,"date":"2019-04-09T12:57:00","date_gmt":"2019-04-09T11:57:00","guid":{"rendered":"https:\/\/busot.es\/publica\/2019\/04\/09\/concierto-festero\/"},"modified":"2019-04-09T12:57:00","modified_gmt":"2019-04-09T11:57:00","slug":"concierto-festero","status":"publish","type":"post","link":"https:\/\/busot.es\/publica\/2019\/04\/09\/concierto-festero\/","title":{"rendered":"CONCIERTO FESTERO"},"content":{"rendered":"[ad_1]\nCONCIERTO FESTERO<br \/>\nComo cada a\u00f1o, la Uni\u00f3 Musical Busot dar\u00e1 su Concierto Festero, para celebrar las Fiestas de Moros y Cristianos de nuestro pueblo. Es la XXIV Campa\u00f1a M\u00fasica a los Pueblos de la Diputaci\u00f3n de Alicante. Os esperamos el 13 de abril, a las 19:00 en la Casa de Cultura.<\/p>\n<p> <a href=\"https:\/\/www.facebook.com\/hashtag\/FestesdeBusot\">#FestesdeBusot<\/a>  <a href=\"https:\/\/www.facebook.com\/hashtag\/MyC2019Busot\">#MyC2019Busot<\/a><\/p>\n<p>CONCERT FESTER<br \/>\nCom cada any, la Uni\u00f3 Musical de Busot donar\u00e0 el seu Concert Fester, per a celebrar les Festes de Moros i Cristians del nostre poble. \u00c9s la XXIV Campa\u00f1a M\u00fasica als Pobles de la Diputaci\u00f3n de Alicante. Us esperem el 13 d&#8217;abril, a les 19:00 en la Casa de Cultura.<\/p>\n<p><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/scontent.xx.fbcdn.net\/v\/t1.0-9\/s720x720\/55708893_2134759106616918_6543888991970656256_o.jpg?_nc_cat=101&#038;_nc_ht=scontent.xx&#038;oh=5697ed55bd69252d9469661084eef7d3&#038;oe=5D336777\" \/><br \/>\n[ad_2]\n<br \/><a href=\"https:\/\/www.facebook.com\/135079353251580\/posts\/2134759429950219\">Ver en facebook<\/a>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] CONCIERTO FESTERO Como cada a\u00f1o, la Uni\u00f3 Musical Busot dar\u00e1 su Concierto Festero, para celebrar las Fiestas de Moros y Cristianos de nuestro pueblo. Es la XXIV Campa\u00f1a M\u00fasica a los Pueblos de la Diputaci\u00f3n de Alicante. Os esperamos el 13 de abril, a las 19:00 en la Casa de Cultura. #FestesdeBusot #MyC2019Busot CONCERT [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[39,38],"tags":[],"class_list":["post-14084","post","type-post","status-publish","format-standard","hentry","category-facebook","category-noticias"],"_links":{"self":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts\/14084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/comments?post=14084"}],"version-history":[{"count":0,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/posts\/14084\/revisions"}],"wp:attachment":[{"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/media?parent=14084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/categories?post=14084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/busot.es\/publica\/wp-json\/wp\/v2\/tags?post=14084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}